{"id":1759,"count":1,"description":"","link":"https:\/\/www.quotesdir.com\/es\/tag\/george-washington-carver\/","name":"George Washington Carver","slug":"george-washington-carver","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.quotesdir.com\/es\/wp-json\/wp\/v2\/tags\/1759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quotesdir.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.quotesdir.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.quotesdir.com\/es\/wp-json\/wp\/v2\/posts?tags=1759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}